{"id":678,"date":"2020-05-21T12:51:56","date_gmt":"2020-05-21T10:51:56","guid":{"rendered":"https:\/\/www.fluidpower.it\/regles-dassemblage-pour-les-bouchons\/"},"modified":"2020-05-21T12:51:57","modified_gmt":"2020-05-21T10:51:57","slug":"regles-dassemblage-pour-les-bouchons","status":"publish","type":"post","link":"https:\/\/www.fluidpower.it\/fr\/regles-dassemblage-pour-les-bouchons\/","title":{"rendered":"R\u00e8gles d'assemblage pour les bouchons"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"678\" class=\"elementor elementor-678 elementor-602\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-440cd10 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"440cd10\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9a497a0\" data-id=\"9a497a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-89ac80a elementor-widget elementor-widget-text-editor\" data-id=\"89ac80a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pour MDTools, il existe 2 types de bouchons: filet\u00e9s ou Expander.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3016ebb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3016ebb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-740fee9\" data-id=\"740fee9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c5bdd71 elementor-widget elementor-widget-text-editor\" data-id=\"c5bdd71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Exemple de cavit\u00e9 pour bouchon filet\u00e9<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3b6174f\" data-id=\"3b6174f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dbecb24 elementor-widget elementor-widget-text-editor\" data-id=\"dbecb24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Example de cavit\u00e9 pour Expander<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a44e384 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a44e384\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b6d9a7c\" data-id=\"b6d9a7c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-368308c elementor-widget elementor-widget-image\" data-id=\"368308c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"235\" src=\"https:\/\/www.fluidpower.it\/files\/2020\/05\/PlugCavity-300x235.png\" class=\"attachment-medium size-medium wp-image-609\" alt=\"\" srcset=\"https:\/\/www.fluidpower.it\/files\/2020\/05\/PlugCavity-300x235.png 300w, https:\/\/www.fluidpower.it\/files\/2020\/05\/PlugCavity.png 429w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e5b321e\" data-id=\"e5b321e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a903f1f elementor-widget elementor-widget-image\" data-id=\"a903f1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"273\" src=\"https:\/\/www.fluidpower.it\/files\/2020\/05\/ExpCavity-300x273.png\" class=\"attachment-medium size-medium wp-image-606\" alt=\"\" srcset=\"https:\/\/www.fluidpower.it\/files\/2020\/05\/ExpCavity-300x273.png 300w, https:\/\/www.fluidpower.it\/files\/2020\/05\/ExpCavity.png 356w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-324fe85 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"324fe85\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-93658cf\" data-id=\"93658cf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff9e62b elementor-widget elementor-widget-text-editor\" data-id=\"ff9e62b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dans les deux cas, le STEP0 de la cavit\u00e9 doit \u00eatre identifi\u00e9. Ci-dessous est montr\u00e9 comment les bouchons doivent \u00eatre assembl\u00e9s dans le mod\u00e8le 3D.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0a2044e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0a2044e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d143c13\" data-id=\"d143c13\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-282971c elementor-widget elementor-widget-image\" data-id=\"282971c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"291\" src=\"https:\/\/www.fluidpower.it\/files\/2020\/05\/PlugAssembled-300x291.png\" class=\"attachment-medium size-medium wp-image-612\" alt=\"\" srcset=\"https:\/\/www.fluidpower.it\/files\/2020\/05\/PlugAssembled-300x291.png 300w, https:\/\/www.fluidpower.it\/files\/2020\/05\/PlugAssembled.png 326w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1c41958\" data-id=\"1c41958\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e4de59 elementor-widget elementor-widget-image\" data-id=\"3e4de59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"291\" src=\"https:\/\/www.fluidpower.it\/files\/2020\/05\/ExpAssembled-300x291.png\" class=\"attachment-medium size-medium wp-image-615\" alt=\"\" srcset=\"https:\/\/www.fluidpower.it\/files\/2020\/05\/ExpAssembled-300x291.png 300w, https:\/\/www.fluidpower.it\/files\/2020\/05\/ExpAssembled.png 326w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8343b23 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8343b23\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a73369d\" data-id=\"a73369d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bb7bf6f elementor-widget elementor-widget-text-editor\" data-id=\"bb7bf6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les bouchons filet\u00e9s respectent les r\u00e8gles de montage \u00ab\u00a0Cartridge Valve\u00a0\u00bb. Dans cette section, ils sont demand\u00e9s<br \/>\nFace sup\u00e9rieure = pas pertinent mais vous devez le s\u00e9lectionner (s\u00e9lectionner la face externe du capuchon)<br \/>\nFace inf\u00e9rieure = Le plan qui doit \u00eatre plac\u00e9 contre le STEP0 de la cavit\u00e9<br \/>\nAxe = axe du bouchon (axe du cylindre filet\u00e9)<\/p>\n<p>Il est possible de s\u00e9lectionner des faces planes dans le mod\u00e8le 3D au lieu de plans. Si les faces ne sont pas planes, il est possible de cr\u00e9er des plans avec les commandes du modeleur CAO et de les utiliser.<\/p>\n<p>Si le bouchon est assembl\u00e9 \u00e0 l&rsquo;envers, il est n\u00e9cessaire d&rsquo;inverser la normale du plan \u00e0 l&rsquo;aide des commandes appropri\u00e9es Inventor ou SolidWorks.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-63689e8\" data-id=\"63689e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ba0cbe elementor-widget elementor-widget-text-editor\" data-id=\"6ba0cbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Expander suit les r\u00e8gles d&rsquo;assemblage de \u00ab\u00a0Expander Plug\u00a0\u00bb. Pour la s\u00e9rie MDTools 700 (Inventor), seul le bord inf\u00e9rieur est suffisant,<br \/>\nLa s\u00e9rie MDTools 900 pour SolidWorks n\u00e9cessite deux contraintes, Bord inf\u00e9rieur et Face inf\u00e9rieure pour une gestion diff\u00e9rente des contraintes du moteur CAO.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7c805bb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7c805bb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-cae815b\" data-id=\"cae815b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b679046 elementor-widget elementor-widget-image\" data-id=\"b679046\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"292\" src=\"https:\/\/www.fluidpower.it\/files\/2020\/05\/Constraints_CV-300x292.png\" class=\"attachment-medium size-medium wp-image-618\" alt=\"\" srcset=\"https:\/\/www.fluidpower.it\/files\/2020\/05\/Constraints_CV-300x292.png 300w, https:\/\/www.fluidpower.it\/files\/2020\/05\/Constraints_CV.png 325w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4a9a87f\" data-id=\"4a9a87f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dfce76d elementor-widget elementor-widget-image\" data-id=\"dfce76d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"292\" src=\"https:\/\/www.fluidpower.it\/files\/2020\/05\/Constraints_exp-300x292.png\" class=\"attachment-medium size-medium wp-image-621\" alt=\"\" srcset=\"https:\/\/www.fluidpower.it\/files\/2020\/05\/Constraints_exp-300x292.png 300w, https:\/\/www.fluidpower.it\/files\/2020\/05\/Constraints_exp.png 325w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-16bdf6d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"16bdf6d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a27bcac\" data-id=\"a27bcac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28861d3 elementor-widget elementor-widget-text-editor\" data-id=\"28861d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Voici quelques dossiers zip avec des mod\u00e8les CAO 3D de bouchons pr\u00eats \u00e0 \u00eatre assembl\u00e9s avec MDTools<br \/>\nLes mod\u00e8les 3D ont \u00e9t\u00e9 t\u00e9l\u00e9charg\u00e9s depuis <a href=\"https:\/\/bossard.partcommunity.com\/3d-cad-models\">la communaut\u00e9 Bossard Part<\/a> et depuis <a href=\"https:\/\/www.parker.com\/\">parker.com<\/a><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ad34824 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ad34824\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7999777\" data-id=\"7999777\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-219f453 elementor-widget elementor-widget-text-editor\" data-id=\"219f453\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Autodesk Inventor 2020<\/p>\n<p><a href=\"https:\/\/www.fluidpower.it\/files\/2020\/05\/INV2020_BSP.zip\">Bouchons BSP<\/a><br \/>\n<a href=\"https:\/\/www.fluidpower.it\/files\/2020\/05\/INV2020_EXPANDER.zip\">Bouchons Expander<\/a><br \/>\n<a href=\"https:\/\/www.fluidpower.it\/files\/2020\/05\/INV2020_SAE.zip\">Bouchons SAE<\/a><br \/>\n<a href=\"https:\/\/www.fluidpower.it\/files\/2020\/05\/INV2020_Metric.zip\">Bouchons M\u00e9triques<\/a><br \/>\n<a href=\"https:\/\/www.fluidpower.it\/files\/2020\/05\/INV2020_NPTF.zip\">Bouchons NPTF<\/a><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c2f9542\" data-id=\"c2f9542\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f99b903 elementor-widget elementor-widget-text-editor\" data-id=\"f99b903\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>SolidWorks 2020<\/p>\n<p><a href=\"https:\/\/www.fluidpower.it\/files\/2020\/05\/SW2020_BSP.zip\">Bouchons BSP<\/a><br \/>\n<a href=\"https:\/\/www.fluidpower.it\/files\/2020\/05\/SW2020_Expander.zip\">Bouchons Expander<\/a><br \/>\n<a href=\"https:\/\/www.fluidpower.it\/files\/2020\/05\/SW2020_SAE.zip\">Bouchons SAE<\/a><br \/>\n<a href=\"https:\/\/www.fluidpower.it\/files\/2020\/05\/SW2020_Metric.zip\">Bouchons M\u00e9triques<\/a><br \/>\n<a href=\"https:\/\/www.fluidpower.it\/files\/2020\/05\/SW2020_NPTF.zip\">Bouchons NPTF<\/a><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Pour MDTools, il existe 2 types de bouchons: filet\u00e9s ou Expander. Exemple de cavit\u00e9 pour bouchon filet\u00e9 Example de cavit\u00e9 pour Expander Dans les deux cas, le STEP0 de la cavit\u00e9 doit \u00eatre identifi\u00e9. Ci-dessous est montr\u00e9 comment les bouchons doivent \u00eatre assembl\u00e9s dans le mod\u00e8le 3D. Les bouchons filet\u00e9s respectent les r\u00e8gles de montage ... <a title=\"R\u00e8gles d&#039;assemblage pour les bouchons\" class=\"read-more\" href=\"https:\/\/www.fluidpower.it\/fr\/regles-dassemblage-pour-les-bouchons\/\" aria-label=\"En savoir plus sur R\u00e8gles d&#039;assemblage pour les bouchons\">Read more<\/a><\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"generate_page_header":"","footnotes":""},"categories":[88,102],"tags":[],"class_list":["post-678","post","type-post","status-publish","format-standard","hentry","category-mdtools-training-fr","category-montage"],"_links":{"self":[{"href":"https:\/\/www.fluidpower.it\/fr\/wp-json\/wp\/v2\/posts\/678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fluidpower.it\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fluidpower.it\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fluidpower.it\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fluidpower.it\/fr\/wp-json\/wp\/v2\/comments?post=678"}],"version-history":[{"count":0,"href":"https:\/\/www.fluidpower.it\/fr\/wp-json\/wp\/v2\/posts\/678\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fluidpower.it\/fr\/wp-json\/wp\/v2\/media?parent=678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fluidpower.it\/fr\/wp-json\/wp\/v2\/categories?post=678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fluidpower.it\/fr\/wp-json\/wp\/v2\/tags?post=678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}